{"id":48111,"date":"2023-11-07T11:11:09","date_gmt":"2023-11-07T10:11:09","guid":{"rendered":"https:\/\/harrobia.net\/?p=48111"},"modified":"2023-11-07T11:11:09","modified_gmt":"2023-11-07T10:11:09","slug":"el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro","status":"publish","type":"post","link":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/","title":{"rendered":"El alumnado del ciclo \u00ab3D y Videojuegos\u00bb de Harrobia Ikastola colaboran con el actor Pablo Pi\u00f1eiro"},"content":{"rendered":"<p>El alumnado de segundo curso del ciclo superior \u00abAnimaci\u00f3n 3D, videojuegos y entornos interactivos\u00bb de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro para llevar un guion que este \u00faltimo ha escrito, a un cortometraje de animaci\u00f3n. El cortometraje de Pi\u00f1eiro trata sobre la igualdad de g\u00e9nero \u26a7y las responsabilidades emocionales, contando la historia de unos \u00abCaballitos de Mar\u00bb.<\/p>\n<p>Ayer, <a class=\"PressableText x1i10hfl xjbqb8w x6umtig x1b1mbwd xaqea5y xav7gou x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz PolarisHashtagLink  _aa9_ _a6hd\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.instagram.com\/explore\/tags\/pablopi%C3%B1eiro\/\">@PabloPi\u00f1eiro<\/a>\u00a0vino a la ikastola a reunirse con nuestro alumnado; le ha gustado mucho lo hecho hasta ahora y han hablado de las mejoras y estrategias necesarias.<\/p>\n<p>Nuestro alumnado lleva dos meses trabajando y les queda mucho camino para terminar este cortometraje, pero esperan tenerlo listo para finales de 2024 .<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>El alumnado de segundo curso del ciclo superior \u00abAnimaci\u00f3n 3D, videojuegos y entornos interactivos\u00bb de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro para llevar un guion que este \u00faltimo ha escrito, a un cortometraje de animaci\u00f3n. El cortometraje de Pi\u00f1eiro trata sobre la igualdad de g\u00e9nero \u26a7y las responsabilidades emocionales, contando la historia de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":48109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[604,586],"tags":[],"class_list":["post-48111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3d-gamificacion-y-videojuegos","category-ciclos-fp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Harrobia | Lanbide heziketa Bizkaian<\/title>\n<meta name=\"description\" content=\"El alumnado de segundo curso del ciclo superior &quot;Animaci\u00f3n 3D, videojuegos y entornos interactivos&quot; de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harrobia | Lanbide heziketa Bizkaian\" \/>\n<meta property=\"og:description\" content=\"El alumnado de segundo curso del ciclo superior &quot;Animaci\u00f3n 3D, videojuegos y entornos interactivos&quot; de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Harrobia Ikastola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HarrobiaIkastola\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-07T10:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Harrobia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@harrobiaikas\" \/>\n<meta name=\"twitter:site\" content=\"@harrobiaikas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Harrobia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/\"},\"author\":{\"name\":\"Harrobia\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/#\\\/schema\\\/person\\\/1d744cfed951cc4f6a3fca6f0b31f524\"},\"headline\":\"El alumnado del ciclo \u00ab3D y Videojuegos\u00bb de Harrobia Ikastola colaboran con el actor Pablo Pi\u00f1eiro\",\"datePublished\":\"2023-11-07T10:11:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Harrobia-Ikastola-FP-1.jpg\",\"articleSection\":[\"3D, Gamificaci\u00f3n y Videojuegos\",\"Ciclos FP\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/\",\"url\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/\",\"name\":\"Harrobia | Lanbide heziketa Bizkaian\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Harrobia-Ikastola-FP-1.jpg\",\"datePublished\":\"2023-11-07T10:11:09+00:00\",\"description\":\"El alumnado de segundo curso del ciclo superior \\\"Animaci\u00f3n 3D, videojuegos y entornos interactivos\\\" de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Harrobia-Ikastola-FP-1.jpg\",\"contentUrl\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Harrobia-Ikastola-FP-1.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/es\\\/2023\\\/11\\\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/harrobia.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alumnado del ciclo &#8220;3D y Videojuegos&#8221; de Harrobia Ikastola colaboran con el actor Pablo Pi\u00f1eiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/#website\",\"url\":\"https:\\\/\\\/harrobia.net\\\/\",\"name\":\"Harrobia Ikastola\",\"description\":\"Harrobia Lanbide Heziketaren Ikastola\",\"publisher\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/harrobia.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/#organization\",\"name\":\"Harrobia Ikastola\",\"url\":\"https:\\\/\\\/harrobia.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/harrobia.png\",\"contentUrl\":\"https:\\\/\\\/harrobia.net\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/harrobia.png\",\"width\":256,\"height\":71,\"caption\":\"Harrobia Ikastola\"},\"image\":{\"@id\":\"https:\\\/\\\/harrobia.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HarrobiaIkastola\",\"https:\\\/\\\/x.com\\\/harrobiaikas\",\"https:\\\/\\\/www.instagram.com\\\/harrobiaikastola\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/IbarezkerraBilbo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/harrobia.net\\\/#\\\/schema\\\/person\\\/1d744cfed951cc4f6a3fca6f0b31f524\",\"name\":\"Harrobia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g\",\"caption\":\"Harrobia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harrobia | Lanbide heziketa Bizkaian","description":"El alumnado de segundo curso del ciclo superior \"Animaci\u00f3n 3D, videojuegos y entornos interactivos\" de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/","og_locale":"es_ES","og_type":"article","og_title":"Harrobia | Lanbide heziketa Bizkaian","og_description":"El alumnado de segundo curso del ciclo superior \"Animaci\u00f3n 3D, videojuegos y entornos interactivos\" de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro","og_url":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/","og_site_name":"Harrobia Ikastola","article_publisher":"https:\/\/www.facebook.com\/HarrobiaIkastola","article_published_time":"2023-11-07T10:11:09+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","type":"image\/jpeg"}],"author":"Harrobia","twitter_card":"summary_large_image","twitter_creator":"@harrobiaikas","twitter_site":"@harrobiaikas","twitter_misc":{"Escrito por":"Harrobia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#article","isPartOf":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/"},"author":{"name":"Harrobia","@id":"https:\/\/harrobia.net\/#\/schema\/person\/1d744cfed951cc4f6a3fca6f0b31f524"},"headline":"El alumnado del ciclo \u00ab3D y Videojuegos\u00bb de Harrobia Ikastola colaboran con el actor Pablo Pi\u00f1eiro","datePublished":"2023-11-07T10:11:09+00:00","mainEntityOfPage":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/"},"wordCount":132,"publisher":{"@id":"https:\/\/harrobia.net\/#organization"},"image":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#primaryimage"},"thumbnailUrl":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","articleSection":["3D, Gamificaci\u00f3n y Videojuegos","Ciclos FP"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/","url":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/","name":"Harrobia | Lanbide heziketa Bizkaian","isPartOf":{"@id":"https:\/\/harrobia.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#primaryimage"},"image":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#primaryimage"},"thumbnailUrl":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","datePublished":"2023-11-07T10:11:09+00:00","description":"El alumnado de segundo curso del ciclo superior \"Animaci\u00f3n 3D, videojuegos y entornos interactivos\" de nuestra ikastola trabaja con el actor Pablo Pi\u00f1eiro","breadcrumb":{"@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#primaryimage","url":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","contentUrl":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/harrobia.net\/es\/2023\/11\/el-alumnado-del-ciclo-3d-y-videojuegos-de-harrobia-ikastola-colaboran-con-el-actor-pablo-pineiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/harrobia.net\/"},{"@type":"ListItem","position":2,"name":"El alumnado del ciclo &#8220;3D y Videojuegos&#8221; de Harrobia Ikastola colaboran con el actor Pablo Pi\u00f1eiro"}]},{"@type":"WebSite","@id":"https:\/\/harrobia.net\/#website","url":"https:\/\/harrobia.net\/","name":"Harrobia Ikastola","description":"Harrobia Lanbide Heziketaren Ikastola","publisher":{"@id":"https:\/\/harrobia.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/harrobia.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/harrobia.net\/#organization","name":"Harrobia Ikastola","url":"https:\/\/harrobia.net\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/harrobia.net\/#\/schema\/logo\/image\/","url":"https:\/\/harrobia.net\/wp-content\/uploads\/2014\/07\/harrobia.png","contentUrl":"https:\/\/harrobia.net\/wp-content\/uploads\/2014\/07\/harrobia.png","width":256,"height":71,"caption":"Harrobia Ikastola"},"image":{"@id":"https:\/\/harrobia.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HarrobiaIkastola","https:\/\/x.com\/harrobiaikas","https:\/\/www.instagram.com\/harrobiaikastola","https:\/\/www.youtube.com\/user\/IbarezkerraBilbo"]},{"@type":"Person","@id":"https:\/\/harrobia.net\/#\/schema\/person\/1d744cfed951cc4f6a3fca6f0b31f524","name":"Harrobia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1612bf25e223eceb52dad98cf1059e32644be96e26361dd982cbd02be97556f3?s=96&d=mm&r=g","caption":"Harrobia"}}]}},"jetpack_featured_media_url":"https:\/\/harrobia.net\/wp-content\/uploads\/2023\/11\/Harrobia-Ikastola-FP-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/posts\/48111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/comments?post=48111"}],"version-history":[{"count":1,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/posts\/48111\/revisions"}],"predecessor-version":[{"id":48112,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/posts\/48111\/revisions\/48112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/media\/48109"}],"wp:attachment":[{"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/media?parent=48111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/categories?post=48111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/harrobia.net\/es\/wp-json\/wp\/v2\/tags?post=48111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}